{"id":32601,"date":"2026-01-16T11:59:57","date_gmt":"2026-01-16T04:59:57","guid":{"rendered":"https:\/\/real-riders.com\/?post_type=product&#038;p=32601"},"modified":"2026-01-29T12:01:47","modified_gmt":"2026-01-29T05:01:47","slug":"%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7","status":"publish","type":"product","link":"https:\/\/real-riders.com\/en\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/","title":{"rendered":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face &#8211; Sport &#038; Racing \/ PEARL WHITE"},"content":{"rendered":"<p class=\"QN2lPu\">\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11<\/p>\n<p class=\"QN2lPu\">\u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e0a\u0e34\u0e25\u0e14\u0e4c\u0e2b\u0e19\u0e49\u0e32 Max Vision \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 UV-A &amp; B 99% \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22\u0e02\u0e35\u0e14\u0e02\u0e48\u0e27\u0e19<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e25\u0e21\u0e40\u0e02\u0e49\u0e32\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 2 \u0e0a\u0e48\u0e2d\u0e07 \u0e1a\u0e19\u0e28\u0e23\u0e35\u0e29\u0e30<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 ACS \u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1a\u0e19\u0e42\u0e1f\u0e21\u0e2b\u0e21\u0e27\u0e01 \u0e16\u0e48\u0e32\u0e22\u0e40\u0e17\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19 \u0e25\u0e14\u0e2d\u0e38\u0e13\u0e20\u0e39\u0e21\u0e34\u0e1a\u0e19\u0e28\u0e23\u0e35\u0e29\u0e30 \u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e2b\u0e21\u0e27\u0e01<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e27\u0e48\u0e19\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e19\u0e27\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19 Quick Dry \u0e41\u0e2b\u0e49\u0e07\u0e44\u0e27 \u0e19\u0e38\u0e48\u0e21\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e04\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e25\u0e39\u0e17\u0e39\u0e18 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e21\u0e35\u0e0a\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e49\u0e32\u0e2b\u0e39 \u0e44\u0e21\u0e48\u0e1a\u0e35\u0e1a\u0e43\u0e1a\u0e2b\u0e39 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07\u0e41\u0e1a\u0e1a DD-Ring \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 SNELL M2025D<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 DOT<\/p>\n<p class=\"QN2lPu\">&#8211; \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e21\u0e2d\u0e01.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL &#8211; \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 &#8211; \u0e0a\u0e34\u0e25\u0e14\u0e4c\u0e2b\u0e19\u0e49\u0e32 Max Vision<\/p>\n","protected":false},"featured_media":32602,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_cat":[81,76],"product_tag":[],"class_list":["post-32601","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-hjc","product_cat-helmet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport &amp; Racing \/ PEARL WHITE - REALRIDER<\/title>\n<meta name=\"description\" content=\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/real-riders.com\/product\/\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04-hjc-\u0e23\u0e38\u0e48\u0e19-i11-full-face-sport-racing-7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport &amp; Racing \/ PEARL WHITE - REALRIDER\" \/>\n<meta property=\"og:description\" content=\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/real-riders.com\/product\/\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04-hjc-\u0e23\u0e38\u0e48\u0e19-i11-full-face-sport-racing-7\/\" \/>\n<meta property=\"og:site_name\" content=\"REALRIDER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RRbangna\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T05:01:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/real-riders.com\/wp-content\/uploads\/2026\/01\/th-11134207-81zti-mjjc01h17lz67b.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/\",\"name\":\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport & Racing \\\/ PEARL WHITE - REALRIDER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/th-11134207-81zti-mjjc01h17lz67b.png\",\"datePublished\":\"2026-01-16T04:59:57+00:00\",\"dateModified\":\"2026-01-29T05:01:47+00:00\",\"description\":\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/th-11134207-81zti-mjjc01h17lz67b.png\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/th-11134207-81zti-mjjc01h17lz67b.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/real-riders.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\\\/\\\/real-riders.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face &#8211; Sport &#038; Racing \\\/ PEARL WHITE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"name\":\"REALRIDER\",\"description\":\"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\",\"publisher\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/real-riders.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\",\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"width\":500,\"height\":500,\"caption\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RRbangna\",\"https:\\\/\\\/www.instagram.com\\\/realrider_mega\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport & Racing \/ PEARL WHITE - REALRIDER","description":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/real-riders.com\/product\/\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04-hjc-\u0e23\u0e38\u0e48\u0e19-i11-full-face-sport-racing-7\/","og_locale":"en_US","og_type":"article","og_title":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport & Racing \/ PEARL WHITE - REALRIDER","og_description":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -","og_url":"https:\/\/real-riders.com\/product\/\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04-hjc-\u0e23\u0e38\u0e48\u0e19-i11-full-face-sport-racing-7\/","og_site_name":"REALRIDER","article_publisher":"https:\/\/www.facebook.com\/RRbangna","article_modified_time":"2026-01-29T05:01:47+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/real-riders.com\/wp-content\/uploads\/2026\/01\/th-11134207-81zti-mjjc01h17lz67b.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/","url":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/","name":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face - Sport & Racing \/ PEARL WHITE - REALRIDER","isPartOf":{"@id":"https:\/\/real-riders.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/#primaryimage"},"image":{"@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/#primaryimage"},"thumbnailUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2026\/01\/th-11134207-81zti-mjjc01h17lz67b.png","datePublished":"2026-01-16T04:59:57+00:00","dateModified":"2026-01-29T05:01:47+00:00","description":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 \u0e21\u0e35 Size \u0e16\u0e36\u0e07 5XL - \u0e27\u0e31\u0e2a\u0e14\u0e38 Advanced Polycarbonate Shell \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e21\u0e27\u0e01\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 -","breadcrumb":{"@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/#primaryimage","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2026\/01\/th-11134207-81zti-mjjc01h17lz67b.png","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2026\/01\/th-11134207-81zti-mjjc01h17lz67b.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/real-riders.com\/product\/%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b9%87%e0%b8%ad%e0%b8%84-hjc-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99-i11-full-face-sport-racing-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/real-riders.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/real-riders.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 HJC \u0e23\u0e38\u0e48\u0e19 i11 Full Face &#8211; Sport &#038; Racing \/ PEARL WHITE"}]},{"@type":"WebSite","@id":"https:\/\/real-riders.com\/#website","url":"https:\/\/real-riders.com\/","name":"REALRIDER","description":"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c","publisher":{"@id":"https:\/\/real-riders.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/real-riders.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/real-riders.com\/#organization","name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14","url":"https:\/\/real-riders.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","width":500,"height":500,"caption":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14"},"image":{"@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RRbangna","https:\/\/www.instagram.com\/realrider_mega"]}]}},"_links":{"self":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product\/32601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media\/32602"}],"wp:attachment":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media?parent=32601"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_cat?post=32601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_tag?post=32601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}