{"id":28442,"date":"2024-02-20T11:49:46","date_gmt":"2024-02-20T04:49:46","guid":{"rendered":"https:\/\/real-riders.com\/?post_type=product&#038;p=28442"},"modified":"2026-07-20T11:53:55","modified_gmt":"2026-07-20T04:53:55","slug":"real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2","status":"publish","type":"product","link":"https:\/\/real-riders.com\/en\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/","title":{"rendered":"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32"},"content":{"rendered":"<p>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01<br \/>\n\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 :<br \/>\n\u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35<\/p>\n<p>\u0e42\u0e1f\u0e21 :<br \/>\n\u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.) \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35<\/p>\n<p>\u0e0a\u0e38\u0e14\u0e19\u0e27\u0e21 :<br \/>\n\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e23\u0e39\u0e1b\u0e2b\u0e19\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e44\u0e14\u0e49 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e41\u0e16\u0e1a\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e2a\u0e07<\/p>\n<p>\u0e0a\u0e48\u0e2d\u0e07\u0e25\u0e21 :<br \/>\n\u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e25\u0e21\u0e40\u0e02\u0e49\u0e32 2 \u0e0a\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e25\u0e21\u0e2d\u0e2d\u0e01 1 \u0e0a\u0e48\u0e2d\u0e07<\/p>\n<p>\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e21\u0e27\u0e01 :<br \/>\n\u0e2a\u0e35 Clear Chrome Blue \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e25\u0e47\u0e2d\u0e01\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e48\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e41\u0e27\u0e48\u0e19\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e14\u0e49\u0e32\u0e19\u0e43\u0e19 :<br \/>\n\u0e2a\u0e35 Dark Smoke<\/p>\n<p>\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 :<br \/>\n\u0e41\u0e1a\u0e1a Grip Lock (Quick-Release) \u0e40\u0e0b\u0e1f \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/p>\n<p>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a :<br \/>\n\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e25\u0e39\u0e17\u0e39\u0e18<\/p>\n<p>\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 :<br \/>\n\u0e21\u0e2d\u0e01. \u0e41\u0e25\u0e30 ECE. 22-05<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.) \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32<\/p>\n","protected":false},"featured_media":28443,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_cat":[82,76],"product_tag":[],"class_list":["post-28442","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-real","product_cat-helmet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER<\/title>\n<meta name=\"description\" content=\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/real-riders.com\/product\/real-oslo-\u0e2a\u0e35\u0e02\u0e32\u0e27-\u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER\" \/>\n<meta property=\"og:description\" content=\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/real-riders.com\/product\/real-oslo-\u0e2a\u0e35\u0e02\u0e32\u0e27-\u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32-2\/\" \/>\n<meta property=\"og:site_name\" content=\"REALRIDER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RRbangna\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T04:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/real-riders.com\/wp-content\/uploads\/2024\/02\/274.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/\",\"name\":\"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/274.png\",\"datePublished\":\"2024-02-20T04:49:46+00:00\",\"dateModified\":\"2026-07-20T04:53:55+00:00\",\"description\":\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/274.png\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/274.png\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/real-riders.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\\\/\\\/real-riders.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"name\":\"REALRIDER\",\"description\":\"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\",\"publisher\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/real-riders.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\",\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"width\":500,\"height\":500,\"caption\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RRbangna\",\"https:\\\/\\\/www.instagram.com\\\/realrider_mega\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER","description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/real-riders.com\/product\/real-oslo-\u0e2a\u0e35\u0e02\u0e32\u0e27-\u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32-2\/","og_locale":"en_US","og_type":"article","og_title":"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER","og_description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)","og_url":"https:\/\/real-riders.com\/product\/real-oslo-\u0e2a\u0e35\u0e02\u0e32\u0e27-\u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32-2\/","og_site_name":"REALRIDER","article_publisher":"https:\/\/www.facebook.com\/RRbangna","article_modified_time":"2026-07-20T04:53:55+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/real-riders.com\/wp-content\/uploads\/2024\/02\/274.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/","url":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/","name":"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 - REALRIDER","isPartOf":{"@id":"https:\/\/real-riders.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/#primaryimage"},"image":{"@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2024\/02\/274.png","datePublished":"2024-02-20T04:49:46+00:00","dateModified":"2026-07-20T04:53:55+00:00","description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e21\u0e27\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 : \u0e17\u0e33\u0e08\u0e32\u0e01 Acrylonitrile Butadiene Styrene (ABS.) \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e1f\u0e21 : \u0e42\u0e1f\u0e21\u0e41\u0e1a\u0e1a Asian Fit \u0e27\u0e31\u0e2a\u0e14\u0e38 Expanded Polystyrene Foam (EPS.)","breadcrumb":{"@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/#primaryimage","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2024\/02\/274.png","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2024\/02\/274.png","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/real-riders.com\/product\/real-oslo-%e0%b8%aa%e0%b8%b5%e0%b8%82%e0%b8%b2%e0%b8%a7-%e0%b8%ab%e0%b8%a1%e0%b8%a7%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/real-riders.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/real-riders.com\/shop\/"},{"@type":"ListItem","position":3,"name":"REAL OSLO \u0e2a\u0e35\u0e14\u0e33\u0e40\u0e07\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/real-riders.com\/#website","url":"https:\/\/real-riders.com\/","name":"REALRIDER","description":"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c","publisher":{"@id":"https:\/\/real-riders.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/real-riders.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/real-riders.com\/#organization","name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14","url":"https:\/\/real-riders.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","width":500,"height":500,"caption":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14"},"image":{"@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RRbangna","https:\/\/www.instagram.com\/realrider_mega"]}]}},"_links":{"self":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product\/28442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media\/28443"}],"wp:attachment":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media?parent=28442"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_cat?post=28442"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_tag?post=28442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}