{"id":25728,"date":"2023-01-25T11:34:25","date_gmt":"2023-01-25T04:34:25","guid":{"rendered":"https:\/\/real-riders.com\/?post_type=product&#038;p=25728"},"modified":"2023-01-25T14:30:08","modified_gmt":"2023-01-25T07:30:08","slug":"origine-primo-jet-helmets-vintage-matt-black","status":"publish","type":"product","link":"https:\/\/real-riders.com\/en\/product\/origine-primo-jet-helmets-vintage-matt-black\/","title":{"rendered":"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK"},"content":{"rendered":"<p>ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32<br \/>\n\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04<\/p>\n<p>-\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01<br \/>\n-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g<br \/>\n-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22<br \/>\n-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22<br \/>\n-\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ECE-R 22.05 \u0e41\u0e25\u0e30 \u0e21\u0e2d\u0e01.<br \/>\n-\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Visor 3\u0e41\u0e25\u0e305 \u0e08\u0e38\u0e14<br \/>\n*** \u0e41\u0e16\u0e21\u0e1f\u0e23\u0e35!! \u0e41\u0e01\u0e4a\u0e1b\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14\u0e17\u0e38\u0e01\u0e43\u0e1a ***<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g -\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22 -\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22<\/p>\n","protected":false},"featured_media":25734,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_cat":[301,76],"product_tag":[],"class_list":["post-25728","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-origine","product_cat-helmet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER<\/title>\n<meta name=\"description\" content=\"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER\" \/>\n<meta property=\"og:description\" content=\"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/\" \/>\n<meta property=\"og:site_name\" content=\"REALRIDER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RRbangna\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-25T07:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/real-riders.com\/wp-content\/uploads\/2023\/01\/matt-black.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/\",\"name\":\"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/matt-black.jpg\",\"datePublished\":\"2023-01-25T04:34:25+00:00\",\"dateModified\":\"2023-01-25T07:30:08+00:00\",\"description\":\"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/#primaryimage\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/matt-black.jpg\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/matt-black.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/product\\\/origine-primo-jet-helmets-vintage-matt-black\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/real-riders.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\\\/\\\/real-riders.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#website\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"name\":\"REALRIDER\",\"description\":\"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\",\"publisher\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/real-riders.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#organization\",\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"url\":\"https:\\\/\\\/real-riders.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"contentUrl\":\"https:\\\/\\\/real-riders.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REAL-LOGO-favicon.png\",\"width\":500,\"height\":500,\"caption\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\"},\"image\":{\"@id\":\"https:\\\/\\\/real-riders.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RRbangna\",\"https:\\\/\\\/www.instagram.com\\\/realrider_mega\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER","description":"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/","og_locale":"en_US","og_type":"article","og_title":"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER","og_description":"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22","og_url":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/","og_site_name":"REALRIDER","article_publisher":"https:\/\/www.facebook.com\/RRbangna","article_modified_time":"2023-01-25T07:30:08+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/real-riders.com\/wp-content\/uploads\/2023\/01\/matt-black.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/","url":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/","name":"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK - REALRIDER","isPartOf":{"@id":"https:\/\/real-riders.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/#primaryimage"},"image":{"@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/#primaryimage"},"thumbnailUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2023\/01\/matt-black.jpg","datePublished":"2023-01-25T04:34:25+00:00","dateModified":"2023-01-25T07:30:08+00:00","description":"ORIGINE PRIMO JET HELMETS \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04 ORIGINE Primo \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 -\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01-\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 1140+-50g-\u0e19\u0e27\u0e21\u0e41\u0e01\u0e49\u0e21\u0e16\u0e2d\u0e14\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e2a\u0e1a\u0e32\u0e22-\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e04\u0e32\u0e07 \u0e41\u0e1a\u0e1a Grip lock \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22","breadcrumb":{"@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/#primaryimage","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2023\/01\/matt-black.jpg","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2023\/01\/matt-black.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/real-riders.com\/product\/origine-primo-jet-helmets-vintage-matt-black\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/real-riders.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/real-riders.com\/shop\/"},{"@type":"ListItem","position":3,"name":"ORIGINE PRIMO JET HELMETS CLASSIC VINTAGE MATT BLACK"}]},{"@type":"WebSite","@id":"https:\/\/real-riders.com\/#website","url":"https:\/\/real-riders.com\/","name":"REALRIDER","description":"\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e0a\u0e38\u0e14\u0e02\u0e35\u0e48\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c","publisher":{"@id":"https:\/\/real-riders.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/real-riders.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/real-riders.com\/#organization","name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14","url":"https:\/\/real-riders.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/","url":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","contentUrl":"https:\/\/real-riders.com\/wp-content\/uploads\/2021\/05\/REAL-LOGO-favicon.png","width":500,"height":500,"caption":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e44\u0e23\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14"},"image":{"@id":"https:\/\/real-riders.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RRbangna","https:\/\/www.instagram.com\/realrider_mega"]}]}},"_links":{"self":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product\/25728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media\/25734"}],"wp:attachment":[{"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/media?parent=25728"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_cat?post=25728"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/real-riders.com\/en\/wp-json\/wp\/v2\/product_tag?post=25728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}